{"id":11397,"date":"2019-12-27T17:19:29","date_gmt":"2019-12-27T16:19:29","guid":{"rendered":"http:\/\/kassel-spielt.de\/press\/?p=11397"},"modified":"2019-12-27T17:37:33","modified_gmt":"2019-12-27T16:37:33","slug":"rezension-zum-spiel-des-jahres-2019-just-one","status":"publish","type":"post","link":"https:\/\/kassel-spielt.de\/press\/rezension-zum-spiel-des-jahres-2019-just-one\/","title":{"rendered":"Rezension zum &#8222;Spiel des Jahres 2019&#8220;  &#8222;Just one&#8220;"},"content":{"rendered":"\n<p><a href=\"http:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/Justone_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-11399\" src=\"http:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/Justone_2.jpg\" alt=\"\" width=\"300\" height=\"250\"><\/a>Jeder Spieler erh\u00e4lt einen Plastik-Ablage. auf dessen R\u00fcckseite mit einem Boardmarker geschrieben werden kann. Ein Spieler startet als erster Ratender, der einen Begriff erraten muss. Die anderen Spieler versuchen ihm mit assoziativen Begriffen zu helfen. Es ist also ein kooperatives Spiel, bei dem es f\u00fcr die Gruppe darum geht, bei 13 Versuchen m\u00f6glichst viele Begriffe zu erraten.<br>Der ratende Spieler zieht eine Karte, sieht sich aber die Vorderseite nicht an, sondern stellt sie so auf&nbsp; seine Ablage, das die anderen Spieler die darauf geschriebenen Begriffe erkennen k\u00f6nnen. Der ratende Spieler nennt eine Zahl zw. 1-5 und die \u00fcbrigen Spieler wissen nun, um welches Wort es sich handelt. Sie schreiben auf die R\u00fcckseite ihrer Ablage einen assoziativen Begriff, der weder einen Teil des zu erratenden Wortes beinhaltet oder nur einen ebenfalls daf\u00fcr existierendes Wort. Die aufgeschriebenen Begriffe der Mitspieler sollen dem Ratenden helfen, das Wort zu finden.<\/p>\n<p><br><strong>Jetzt kommt dazu eine besondere Regel<\/strong>, die das Spiel aus den \u00fcbrigen Ratespielen hervor hebt.<br><a href=\"http:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/JustOne_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-11398\" src=\"http:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/JustOne_1-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/JustOne_1-300x218.jpg 300w, https:\/\/kassel-spielt.de\/press\/wp-content\/uploads\/2019\/12\/JustOne_1.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>W\u00e4hrend der Ratende die Augen schlie\u00dfen muss, drehen die \u00fcbrigen Spieler ihre Ablagen herum und zeigen sich gegenseitig ihre Begriffe. Alle gleichen oder sich sehr \u00e4hnliche Begriffe werden stillschweigend gel\u00f6scht. Diese Regel verhindert, das eindeutige Assoziationen das Raten zu leicht machen. Die Spieler werden daher eher Begriffe notieren, die etwas &#8222;um die Ecke gedacht&#8220; sind. Jetzt darf der Ratende die Augen wieder \u00f6ffnen und sieht die \u00fcbrig gebliebenen assoziativen Begriffe, aus denen er das richtige Wort erraten muss. Wie viele aus 13 Begriffen wird&nbsp; die Spielerunde erraten?<\/p>\n<p>Geeignet ist das Spiel eher ab 10 Jahren aufw\u00e4rts f\u00fcr Familien und Freundeskreise in fr\u00f6hlicher Partyrunde. (Sylvester w\u00e4re so ein Anlass)<br>Nicht so der Sieg, sondern die Freude am &#8222;mit Worten spielen&#8220; steht im Vordergrund.<br>25,- \u20ac ist der Preis f\u00fcr 7 Boardmarker mit Wischer, sieben Schreib-Ablagen und 110 Karten, auf denen die zu erratenden Begriffe stehen.<br>In den Spielerunden im Verein Kassel spielt e.V.&nbsp; und beim Familienspieletag am 24.11. im Rathaus wurde das Spiel gerne gespielt. <br>Die Spieldauer in gr\u00f6\u00dferer Runde&nbsp; liegt bei 20 &#8211; 30 Minuten.<\/p>\n<p>Geschrieben von Martin Ebel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeder Spieler erh\u00e4lt einen Plastik-Ablage. auf dessen R\u00fcckseite mit einem Boardmarker geschrieben werden kann. Ein Spieler startet als erster Ratender, der einen Begriff erraten muss. Die anderen Spieler versuchen ihm mit assoziativen Begriffen zu helfen. Es ist also ein kooperatives Spiel, bei dem es f\u00fcr die Gruppe darum geht, bei 13 Versuchen m\u00f6glichst viele Begriffe [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-11397","post","type-post","status-publish","format-standard","hentry","category-spiele"],"_links":{"self":[{"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/posts\/11397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/comments?post=11397"}],"version-history":[{"count":4,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/posts\/11397\/revisions"}],"predecessor-version":[{"id":11403,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/posts\/11397\/revisions\/11403"}],"wp:attachment":[{"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/media?parent=11397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/categories?post=11397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kassel-spielt.de\/press\/wp-json\/wp\/v2\/tags?post=11397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}